{"id":17479,"date":"2022-06-27T15:33:35","date_gmt":"2022-06-27T15:33:35","guid":{"rendered":"https:\/\/zecovalve.com\/?p=17479"},"modified":"2022-06-27T15:33:36","modified_gmt":"2022-06-27T15:33:36","slug":"hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve","status":"publish","type":"post","link":"https:\/\/zecovalve.com\/es\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html","title":{"rendered":"Balance hidr\u00e1ulico del sistema HVAC y m\u00e9todo de selecci\u00f3n de la v\u00e1lvula de regulaci\u00f3n el\u00e9ctrica"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-brief-introduction-of-hydraulic-balance-system\">Breve introducci\u00f3n al sistema de equilibrado hidr\u00e1ulico<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los sistemas de calefacci\u00f3n y aire acondicionado deben alcanzar dos objetivos principales:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1. Proporcionar el confort necesario;<\/li><li>2. Conseguir los objetivos anteriores con el m\u00ednimo consumo de energ\u00eda.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, de hecho, ni siquiera el sistema de control m\u00e1s complejo puede ofrecer resultados satisfactorios, y el coste de funcionamiento es elevado.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1. En algunos sitios hace demasiado calor y en otros demasiado fr\u00edo.<\/li><li>2. En algunas salas, es dif\u00edcil arrancar despu\u00e9s de retroceder.<\/li><li>3. La potencia de la instalaci\u00f3n no puede aprovecharse al m\u00e1ximo.<\/li><li>4. Consumo de energ\u00eda superior al previsto.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Fen\u00f3menos comunes de desequilibrio hidr\u00e1ulico<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1. Fen\u00f3menos comunes de desequilibrio de flujo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema es desigual en fr\u00edo y en calor:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>A. Cerca del calor lejos del fr\u00edo (cerca del fr\u00edo lejos del calor) al calentar (fr\u00edo).<\/li><li>B. El volumen de agua de algunas ramas es demasiado grande o demasiado peque\u00f1o.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema de caudal variable est\u00e1 averiado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La carga es estable, pero la v\u00e1lvula de control de la habitaci\u00f3n funciona con frecuencia, lo que provoca una oscilaci\u00f3n frecuente de la temperatura ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El consumo de energ\u00eda de funcionamiento de la bomba es demasiado elevado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tiempo de estabilidad del sistema es demasiado largo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Fen\u00f3menos comunes de desequilibrio de la presi\u00f3n<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La v\u00e1lvula de control produce ruido y vibraciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La v\u00e1lvula reguladora no se puede cerrar, y hay peligro de quemar la v\u00e1lvula cuando es grave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El peso de la v\u00e1lvula de control es demasiado peque\u00f1o, y la curva de la v\u00e1lvula se deforma. El sistema controlado de disipaci\u00f3n de calor lineal se convierte en el sistema controlado de disipaci\u00f3n de calor ascendente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No uniformidad del calor y el fr\u00edo en el sistema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Desalineaci\u00f3n del sistema de caudal variable<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Com\u00fanmente utilizado en el sistema de caudal variable con v\u00e1lvula de equilibrio est\u00e1tico, incluso si cada extremo ha sido depurado y equilibrado durante la depuraci\u00f3n, cuando se utiliza en la pr\u00e1ctica, cuando alg\u00fan extremo se ajusta o se cierra, la diferencia de presi\u00f3n entre los otros extremos cambiar\u00e1. Como resultado, el cambio del volumen de agua de otros terminales no regulados conducir\u00e1 al desequilibrio, que es un fen\u00f3meno de desequilibrio din\u00e1mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La carga es estable, pero el regulador funciona con frecuencia<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de que se produzca el desequilibrio din\u00e1mico, la temperatura de la habitaci\u00f3n fluct\u00faa debido al cambio del caudal de agua a trav\u00e9s del extremo, y el termostato controla la v\u00e1lvula reguladora para ajustar el caudal de agua. En este momento, la carga de la habitaci\u00f3n no ha cambiado. La acci\u00f3n reguladora de la v\u00e1lvula de regulaci\u00f3n se debe a la fluctuaci\u00f3n de la presi\u00f3n del sistema.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sistema de caudal variable<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Las v\u00e1lvulas de regulaci\u00f3n se encargan del control de la energ\u00eda, actuando s\u00f3lo cuando cambia la carga, mientras que las v\u00e1lvulas de equilibrado se encargan del control de la presi\u00f3n y de absorber las fluctuaciones de presi\u00f3n en el sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estabilidad prolongada del sistema<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si un sistema de aire acondicionado no consigue mantener una buena relaci\u00f3n lineal entre la apertura de la v\u00e1lvula de control y la disipaci\u00f3n de calor del equipo de disipaci\u00f3n de calor, provocar\u00e1 frecuentes fluctuaciones en la temperatura de la sala controlada, y el tiempo de estabilidad del sistema ser\u00e1 demasiado largo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ruido y vibraci\u00f3n de la v\u00e1lvula reguladora<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la ecuaci\u00f3n de flujo continuo, el agua tiene un proceso de aceleraci\u00f3n y desaceleraci\u00f3n a medida que fluye a trav\u00e9s de la v\u00e1lvula de control. La presi\u00f3n din\u00e1mica correspondiente tambi\u00e9n tiene un proceso de aumento y disminuci\u00f3n. Seg\u00fan la ecuaci\u00f3n de Bernoulli, la presi\u00f3n est\u00e1tica tiene un proceso de disminuci\u00f3n y aumento. Cuando la presi\u00f3n est\u00e1tica en un punto determinado desciende hasta la presi\u00f3n de vaporizaci\u00f3n correspondiente a la temperatura del agua en ese punto, aparecer\u00e1n burbujas en ese punto y se producir\u00e1 \"cavitaci\u00f3n\", lo que dar\u00e1 lugar a ruidos y vibraciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuanto mayor sea la p\u00e9rdida de carga de la v\u00e1lvula de control, mayor ser\u00e1 la temperatura del agua (sobre todo en invierno).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La v\u00e1lvula reguladora no puede cerrarse, a veces se produce el peligroso fen\u00f3meno de la v\u00e1lvula ardiendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando algunas v\u00e1lvulas de control de extremo del sistema est\u00e1n cerradas, la velocidad de flujo de la tuber\u00eda principal disminuye, por lo que la resistencia a la fricci\u00f3n disminuye, y la diferencia de presi\u00f3n entre los dos extremos de las v\u00e1lvulas de control el\u00e9ctrico de otro extremo aumenta. Cuando la diferencia de presi\u00f3n de cierre de la v\u00e1lvula de control el\u00e9ctrico es mayor que la de la v\u00e1lvula de control el\u00e9ctrico, el conductor de la v\u00e1lvula de control el\u00e9ctrico no puede proporcionar suficiente par para cerrar la v\u00e1lvula de control el\u00e9ctrico, lo que resulta en el fen\u00f3meno de que la v\u00e1lvula no se puede cerrar. En este momento, el terminal est\u00e1 en el estado de sobrecorriente, el controlador continuar\u00e1 requiriendo la acci\u00f3n del motor para cerrar la v\u00e1lvula, pero el hecho no se cierra, el motor contin\u00faa calent\u00e1ndose, si el controlador no tiene funci\u00f3n de protecci\u00f3n de sobrecarga, es f\u00e1cil quemar el motor.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfPor qu\u00e9 se equilibra el sistema hidr\u00e1ulico?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La tecnolog\u00eda del equilibrio hidr\u00e1ulico en los sistemas de calefacci\u00f3n y aire acondicionado es la clave para ahorrar energ\u00eda y mejorar la calidad de la refrigeraci\u00f3n o la calefacci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Problema com\u00fan<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>1. En el sistema de calefacci\u00f3n o aire acondicionado, debido a diversas razones, la mayor\u00eda de los bucles de transmisi\u00f3n y el bucle de la unidad de fuente de calor fr\u00edo tienen desequilibrio hidr\u00e1ulico, de modo que el caudal real que pasa por el usuario final y la unidad no coincide con el caudal de dise\u00f1o.<\/li><li>2. La mayor\u00eda de las bombas se seleccionan demasiado grandes o la bomba funciona en un punto de trabajo inadecuado, con lo que el sistema de agua se encuentra en unas condiciones de funcionamiento de gran caudal y peque\u00f1a diferencia de temperatura, el rendimiento de funcionamiento de la bomba es bajo y el rendimiento de transferencia de calor es bajo.<\/li><li>3. La temperatura ambiente de cada usuario es inconsistente e inestable, la temperatura ambiente cerca de la fuente de calor es alta, y la temperatura ambiente en la fuente de calor lejana es baja. La temperatura ambiente cerca de la fuente de fr\u00edo es baja y la temperatura ambiente lejos de la fuente de fr\u00edo es alta.<\/li><li>4. Para las unidades de fuente de calor o de fuente de fr\u00edo, la unidad no alcanza su potencia nominal, de modo que el n\u00famero de unidades que funcionan realmente supera el n\u00famero de unidades requerido por la carga.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Mejorar el confort<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Aseg\u00farese de que la temperatura ambiente cumpla los requisitos de dise\u00f1o y alcance la temperatura fijada en poco tiempo.<\/li><li>Distribuci\u00f3n razonable del tr\u00e1fico<\/li><li>La v\u00e1lvula de equilibrado hidr\u00e1ulico absorbe el exceso de presi\u00f3n diferencial y controla y ajusta el caudal requerido por el sistema.<\/li><li>Ahorrar energ\u00eda y reducir los costes de explotaci\u00f3n<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Por cada 1 \u00b0C de descenso de la temperatura en un sistema de aire acondicionado, el consumo de energ\u00eda aumenta en 15%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por cada 1 \u00b0C de aumento de la temperatura en un sistema de calefacci\u00f3n, el consumo de energ\u00eda se incrementa en 10%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El concepto b\u00e1sico de la v\u00e1lvula y la clasificaci\u00f3n y selecci\u00f3n de la v\u00e1lvula de equilibrado<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Capacidad de circulaci\u00f3n de la v\u00e1lvula - Kv<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>1. Definici\u00f3n: Cuando la diferencia de presi\u00f3n a trav\u00e9s de la v\u00e1lvula es de 1 bar, el flujo a trav\u00e9s de la v\u00e1lvula cuando la v\u00e1lvula est\u00e1 completamente abierta, en m3 \/ h.<\/li><li>2. C\u00e1lculo:<\/li><li>3. Derivaci\u00f3n de f\u00f3rmulas:<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para la v\u00e1lvula reguladora, cuando el grado de apertura de la v\u00e1lvula no cambia, la capacidad de flujo de la v\u00e1lvula no cambia. La capacidad de caudal de la v\u00e1lvula cambia s\u00f3lo cuando cambia el grado de apertura de la v\u00e1lvula de regulaci\u00f3n. La relaci\u00f3n entre la curva de la v\u00e1lvula de regulaci\u00f3n y el tiempo de asentamiento del sistema.<\/p>","protected":false},"excerpt":{"rendered":"<p>Breve introducci\u00f3n del sistema de equilibrio hidr\u00e1ulico Todos los sistemas de calefacci\u00f3n y aire acondicionado deben lograr dos objetivos principales: 1. Proporcionar el confort requerido; \u2026 <a title=\"Balance hidr\u00e1ulico del sistema HVAC y m\u00e9todo de selecci\u00f3n de la v\u00e1lvula de regulaci\u00f3n el\u00e9ctrica\" class=\"read-more\" href=\"https:\/\/zecovalve.com\/es\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\" aria-label=\"M\u00e1s en Balance hidr\u00e1ulico del sistema HVAC y m\u00e9todo de selecci\u00f3n de v\u00e1lvula reguladora el\u00e9ctrica\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_generate-full-width-content":"","kt_blocks_editor_width":"","footnotes":""},"categories":[1],"tags":[245,1401,5],"class_list":["post-17479","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-system","tag-too","tag-valve","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"featured_image_src_large":false,"author_info":{"display_name":"Jerry","author_link":"https:\/\/zecovalve.com\/es\/author\/jerry"},"comment_info":0,"category_info":[{"term_id":1,"name":"Uncategorized","slug":"uncategorized","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":452,"filter":"raw","cat_ID":1,"category_count":452,"category_description":"","cat_name":"Uncategorized","category_nicename":"uncategorized","category_parent":0}],"tag_info":[{"term_id":245,"name":"system","slug":"system","term_group":0,"term_taxonomy_id":245,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":1401,"name":"too","slug":"too","term_group":0,"term_taxonomy_id":1401,"taxonomy":"post_tag","description":"","parent":0,"count":1,"filter":"raw"},{"term_id":5,"name":"valve","slug":"valve","term_group":0,"term_taxonomy_id":5,"taxonomy":"post_tag","description":"","parent":0,"count":125,"filter":"raw"}],"taxonomy_info":{"category":[{"value":1,"label":"Uncategorized"}],"post_tag":[{"value":245,"label":"system"},{"value":1401,"label":"too"},{"value":5,"label":"valve"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hydraulic Balance of HVAC System and Selection Method of Electric Regulating Valve - ZECO Valve<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zecovalve.com\/es\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hydraulic Balance of HVAC System and Selection Method of Electric Regulating Valve - ZECO Valve\" \/>\n<meta property=\"og:description\" content=\"Brief Introduction of Hydraulic Balance System All heating and air conditioning systems should achieve two main objectives: 1. Provide the required comfort; ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zecovalve.com\/es\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\" \/>\n<meta property=\"og:site_name\" content=\"ZECO Valve\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-27T15:33:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-27T15:33:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\">\n\t<meta name=\"twitter:data1\" content=\"Jerry\">\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data2\" content=\"4 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zecovalve.com\/#website\",\"url\":\"https:\/\/zecovalve.com\/\",\"name\":\"ZECO Valve\",\"description\":\"Industrial Ball Valve, Gate Valve and Globe Valve Manufacturer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/zecovalve.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html#webpage\",\"url\":\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\",\"name\":\"Hydraulic Balance of HVAC System and Selection Method of Electric Regulating Valve - ZECO Valve\",\"isPartOf\":{\"@id\":\"https:\/\/zecovalve.com\/#website\"},\"datePublished\":\"2022-06-27T15:33:35+00:00\",\"dateModified\":\"2022-06-27T15:33:36+00:00\",\"author\":{\"@id\":\"https:\/\/zecovalve.com\/#\/schema\/person\/f65555145e0ef282ff87649309aba6a3\"},\"breadcrumb\":{\"@id\":\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zecovalve.com\/\",\"url\":\"https:\/\/zecovalve.com\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\",\"url\":\"https:\/\/zecovalve.com\/hydraulic-balance-of-hvac-system-and-selection-method-of-electric-regulating-valve.html\",\"name\":\"Hydraulic Balance of HVAC System and Selection Method of Electric Regulating Valve\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/zecovalve.com\/#\/schema\/person\/f65555145e0ef282ff87649309aba6a3\",\"name\":\"Jerry\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/posts\/17479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/comments?post=17479"}],"version-history":[{"count":0,"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/posts\/17479\/revisions"}],"wp:attachment":[{"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/media?parent=17479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/categories?post=17479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zecovalve.com\/es\/wp-json\/wp\/v2\/tags?post=17479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}