{"id":28297,"date":"2024-06-16T15:32:24","date_gmt":"2024-06-16T15:32:24","guid":{"rendered":"https:\/\/zecovalve.com\/?p=28297"},"modified":"2024-06-16T15:32:27","modified_gmt":"2024-06-16T15:32:27","slug":"do-you-need-a-check-valve-on-a-sump-pump","status":"publish","type":"post","link":"https:\/\/zecovalve.com\/pt\/do-you-need-a-check-valve-on-a-sump-pump.html","title":{"rendered":"Voc\u00ea precisa de uma v\u00e1lvula de reten\u00e7\u00e3o em uma bomba de dep\u00f3sito?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">As bombas de dep\u00f3sito s\u00e3o sistemas cr\u00edticos que ajudam a prevenir inunda\u00e7\u00f5es em por\u00f5es. Mas, como qualquer sistema mec\u00e2nico, eles podem falhar com o tempo. Um dos acess\u00f3rios mais importantes que voc\u00ea pode instalar para proteger sua bomba de dep\u00f3sito \u00e9 um <a href=\"https:\/\/zecovalve.com\/pt\/categoria-do-produto\/check-valve\/\">v\u00e1lvula de reten\u00e7\u00e3o<\/a>. Mas voc\u00ea realmente precisa de um?<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-1024x576.jpg\" alt=\"v\u00e1lvula de reten\u00e7\u00e3o em uma bomba de dep\u00f3sito\" class=\"wp-image-28298\" srcset=\"https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-1024x576.jpg 1024w, https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-300x169.jpg 300w, https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-768x432.jpg 768w, https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-18x10.jpg 18w, https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-600x338.jpg 600w, https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-is-a-sump-pump-check-valve\">O que \u00e9 uma v\u00e1lvula de reten\u00e7\u00e3o da bomba do reservat\u00f3rio?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Uma bomba de dep\u00f3sito afasta a \u00e1gua da funda\u00e7\u00e3o da sua casa e leva-a para um ponto de descarga seguro. A v\u00e1lvula de reten\u00e7\u00e3o garante que, uma vez que a \u00e1gua saia da bomba, ela s\u00f3 possa fluir em uma dire\u00e7\u00e3o \u2013 longe de casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sem uma v\u00e1lvula de reten\u00e7\u00e3o, a \u00e1gua fluir\u00e1 de volta para o po\u00e7o quando a bomba for desligada. Isso \u00e9 chamado de refluxo. O refluxo for\u00e7a a bomba a ligar com mais frequ\u00eancia para remover a mesma \u00e1gua novamente. A ciclagem frequente pode fazer com que a bomba do reservat\u00f3rio se desgaste mais rapidamente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-how-a-check-valve-stops-backflow\">Como uma v\u00e1lvula de reten\u00e7\u00e3o interrompe o refluxo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Uma v\u00e1lvula de reten\u00e7\u00e3o oscilante b\u00e1sica usa a gravidade para fechar a v\u00e1lvula quando a \u00e1gua para de fluir. Uma aba dentro da v\u00e1lvula desce sobre a abertura quando a bomba \u00e9 desligada. Isso evita que a \u00e1gua flua para tr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00e1lvulas de reten\u00e7\u00e3o mais avan\u00e7adas usam uma mola para fechar. As v\u00e1lvulas de reten\u00e7\u00e3o com mola fecham lenta e silenciosamente. As v\u00e1lvulas de reten\u00e7\u00e3o b\u00e1sicas fecham rapidamente com um \u201cclunk\u201d aud\u00edvel.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-do-you-need-a-check-valve-on-a-sump-pump\">Voc\u00ea precisa de uma v\u00e1lvula de reten\u00e7\u00e3o em uma bomba de dep\u00f3sito?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sim, voc\u00ea precisa de uma v\u00e1lvula de reten\u00e7\u00e3o em uma bomba de dep\u00f3sito. A instala\u00e7\u00e3o de uma v\u00e1lvula de reten\u00e7\u00e3o em sua bomba de dep\u00f3sito \u00e9 essencial para evitar refluxo, reduzir ciclos curtos, proteger a bomba contra danos e garantir uma opera\u00e7\u00e3o eficiente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-why-should-you-install-a-check-valve\">Por que voc\u00ea deve instalar uma v\u00e1lvula de reten\u00e7\u00e3o?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Existem duas raz\u00f5es principais para usar uma v\u00e1lvula de reten\u00e7\u00e3o da bomba do reservat\u00f3rio:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-save-electricity\">1. Economize eletricidade<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Interromper o refluxo evita ciclos desnecess\u00e1rios da bomba do reservat\u00f3rio. Sem uma v\u00e1lvula de reten\u00e7\u00e3o, a \u00e1gua flui de volta para o po\u00e7o sempre que a bomba \u00e9 desligada. Isso pode dobrar ou triplicar o n\u00famero de vezes que sua bomba precisa ser ligada para manter a \u00e1gua em movimento. Mais ciclos = contas de energia el\u00e9trica mais altas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-extend-pump-life\">2. Prolongue a vida \u00fatil da bomba<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ciclos frequentes de ligar\/desligar sobrecarregam o motor da bomba. Motores que funcionam a quente t\u00eam uma vida \u00fatil mais curta. A instala\u00e7\u00e3o de uma v\u00e1lvula de reten\u00e7\u00e3o proporciona \u00e0 bomba do reservat\u00f3rio intervalos mais longos entre os ciclos de funcionamento. Menos tens\u00e3o e calor prolongam a vida \u00fatil da bomba.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-happens-without-a-check-valve\">O que acontece sem uma v\u00e1lvula de reten\u00e7\u00e3o?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Operar uma bomba de dep\u00f3sito sem v\u00e1lvula de reten\u00e7\u00e3o causa dois problemas principais:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-short-cycling\">1. Ciclismo curto<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ciclos curtos referem-se a ciclos frequentes de ligar\/desligar a bomba que acontecem pr\u00f3ximos uns dos outros. Por exemplo, algumas bombas de dep\u00f3sito podem ligar e desligar mais de 200 vezes por dia \u2013 quase uma vez a cada 5 minutos! Esta frequ\u00eancia extrema sobrecarrega o motor e pode levar \u00e0 falha prematura.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-ineffective-dewatering\">2. Desidrata\u00e7\u00e3o ineficaz<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Em cada ciclo, uma bomba de dep\u00f3sito remove menos \u00e1gua sem v\u00e1lvula de reten\u00e7\u00e3o. Por exemplo, uma bomba pode remover 10 gal\u00f5es de \u00e1gua e depois desligar. Sem uma v\u00e1lvula de reten\u00e7\u00e3o, 6 gal\u00f5es fluem imediatamente para tr\u00e1s. Portanto, a remo\u00e7\u00e3o l\u00edquida por ciclo \u00e9 de apenas 4 gal\u00f5es (10 gal\u00f5es de sa\u00edda menos 6 gal\u00f5es de volta).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-where-should-you-install-a-check-valve\">Onde voc\u00ea deve instalar uma v\u00e1lvula de reten\u00e7\u00e3o?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sempre verifique as instru\u00e7\u00f5es do fabricante da bomba para a coloca\u00e7\u00e3o espec\u00edfica da v\u00e1lvula de reten\u00e7\u00e3o. Mas em geral:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Instale a v\u00e1lvula de reten\u00e7\u00e3o no m\u00ednimo 6 polegadas acima da descarga da bomba. Isso deixa espa\u00e7o para fazer um furo de sangria abaixo da v\u00e1lvula para evitar bloqueios de ar.<\/li>\n\n\n\n<li>Posicione a v\u00e1lvula logo abaixo do n\u00edvel do ch\u00e3o para facilitar o acesso. Escolha um local acess\u00edvel para futuras inspe\u00e7\u00f5es e manuten\u00e7\u00f5es.<\/li>\n\n\n\n<li>Nunca exceda 18 polegadas acima do ch\u00e3o. A montagem da v\u00e1lvula muito alta permite um refluxo excessivo entre os ciclos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A gravidade puxa a \u00e1gua de volta para o po\u00e7o atrav\u00e9s do tubo de descarga. A montagem da v\u00e1lvula de reten\u00e7\u00e3o pr\u00f3xima ao ch\u00e3o minimiza a \u201ccoluna\u201d de \u00e1gua que pode fluir para tr\u00e1s.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-signs-you-need-a-check-valve\">Sinais de que voc\u00ea precisa de uma v\u00e1lvula de reten\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Notou algum desses problemas? Voc\u00ea provavelmente precisar\u00e1 instalar uma v\u00e1lvula de reten\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ciclo frequente da bomba mais de 10 vezes por hora<\/li>\n\n\n\n<li>O po\u00e7o \u00e9 reabastecido rapidamente ap\u00f3s a bomba ser desligada<\/li>\n\n\n\n<li>Deve operar a bomba manualmente para reduzir efetivamente a \u00e1gua<\/li>\n\n\n\n<li>Alta umidade no por\u00e3o ap\u00f3s chuva forte<\/li>\n\n\n\n<li>Sinais de inunda\u00e7\u00f5es anteriores no por\u00e3o<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Qualquer um destes indica que a bomba do reservat\u00f3rio trabalha muito para remover a \u00e1gua. A instala\u00e7\u00e3o de uma v\u00e1lvula de reten\u00e7\u00e3o pode resolver esses problemas comuns.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tips-for-installing-a-sump-pump-check-valve\">Dicas para instalar uma v\u00e1lvula de reten\u00e7\u00e3o da bomba do reservat\u00f3rio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Instalar uma v\u00e1lvula de reten\u00e7\u00e3o \u00e9 um projeto DIY simples. Mas aqui est\u00e3o algumas dicas para que o trabalho corra bem:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Desligue a bomba do reservat\u00f3rio antes de iniciar<\/li>\n\n\n\n<li>Escolha a v\u00e1lvula de di\u00e2metro correto para o seu tubo de descarga<\/li>\n\n\n\n<li>Certifique-se de que a seta de fluxo aponta para CIMA, longe do po\u00e7o<\/li>\n\n\n\n<li>Se estiver usando <a href=\"https:\/\/en.wikipedia.org\/wiki\/Plastic_cement\">Cimento de PVC<\/a>, d\u00ea \u00e0s articula\u00e7\u00f5es 30 minutos para curar antes de testar<\/li>\n\n\n\n<li>Teste quanto a vazamentos e opera\u00e7\u00e3o adequada antes de sair do local<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Com uma v\u00e1lvula de reten\u00e7\u00e3o simples, voc\u00ea poder\u00e1 ouvir um som de \u201cclunk\u201d quando a v\u00e1lvula cair durante o teste. Esta \u00e9 uma opera\u00e7\u00e3o normal. As v\u00e1lvulas de reten\u00e7\u00e3o avan\u00e7adas fecham lenta e silenciosamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-maintain-your-check-valve\">Mantenha sua v\u00e1lvula de reten\u00e7\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora as v\u00e1lvulas de reten\u00e7\u00e3o da bomba do reservat\u00f3rio exijam pouca manuten\u00e7\u00e3o, voc\u00ea deve inspecionar a sua periodicamente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Verifique visualmente se h\u00e1 rachaduras ou danos<\/li>\n\n\n\n<li>Garanta uma opera\u00e7\u00e3o desobstru\u00edda<\/li>\n\n\n\n<li>Limpe quaisquer detritos, minerais ou outros dep\u00f3sitos<\/li>\n\n\n\n<li>Confirme a folga de giro adequada ao redor<\/li>\n\n\n\n<li>Substitua se a aba, a sede ou as veda\u00e7\u00f5es parecerem desgastadas<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusion\">Conclus\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Embora as v\u00e1lvulas de reten\u00e7\u00e3o n\u00e3o sejam um requisito absoluto para sistemas de bomba de dep\u00f3sito, elas s\u00e3o altamente recomendadas. Interromper o refluxo economiza eletricidade desperdi\u00e7ada por ciclos desnecess\u00e1rios de funcionamento da bomba. E a elimina\u00e7\u00e3o de ciclos curtos prolonga a vida \u00fatil da sua bomba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea notar sinais de tens\u00e3o em seu sistema de drenagem de po\u00e7o, adicionar uma v\u00e1lvula de reten\u00e7\u00e3o dever\u00e1 ajudar a otimizar o desempenho. Apenas certifique-se de instal\u00e1-lo corretamente e inspecion\u00e1-lo periodicamente como parte de sua rotina geral de manuten\u00e7\u00e3o. Proteger sua bomba de dep\u00f3sito \u00e9 igual a proteger seu por\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>As bombas de dep\u00f3sito s\u00e3o sistemas cr\u00edticos que ajudam a prevenir inunda\u00e7\u00f5es em por\u00f5es. Mas, como qualquer sistema mec\u00e2nico, eles podem falhar com o tempo. \u2026 <a title=\"Voc\u00ea precisa de uma v\u00e1lvula de reten\u00e7\u00e3o em uma bomba de dep\u00f3sito?\" class=\"read-more\" href=\"https:\/\/zecovalve.com\/pt\/do-you-need-a-check-valve-on-a-sump-pump.html\" aria-label=\"Mais em Voc\u00ea precisa de uma v\u00e1lvula de reten\u00e7\u00e3o em uma bomba de dep\u00f3sito?\">Ler mais<\/a><\/p>","protected":false},"author":6,"featured_media":28298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_generate-full-width-content":"","kt_blocks_editor_width":"","footnotes":""},"categories":[2341],"tags":[158,176,5],"class_list":["post-28297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-check-valve","tag-check","tag-pump","tag-valve","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50"],"featured_image_src_large":["https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump-1024x576.jpg",1024,576,true],"author_info":{"display_name":"ZECO Valve","author_link":"https:\/\/zecovalve.com\/pt\/author\/zeco-valve"},"comment_info":0,"category_info":[{"term_id":2341,"name":"Check Valve","slug":"check-valve","term_group":0,"term_taxonomy_id":2341,"taxonomy":"category","description":"Check Valve Description","parent":0,"count":30,"filter":"raw","cat_ID":2341,"category_count":30,"category_description":"Check Valve Description","cat_name":"Check Valve","category_nicename":"check-valve","category_parent":0}],"tag_info":[{"term_id":158,"name":"check","slug":"check","term_group":0,"term_taxonomy_id":158,"taxonomy":"post_tag","description":"","parent":0,"count":25,"filter":"raw"},{"term_id":176,"name":"pump","slug":"pump","term_group":0,"term_taxonomy_id":176,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw"},{"term_id":5,"name":"valve","slug":"valve","term_group":0,"term_taxonomy_id":5,"taxonomy":"post_tag","description":"","parent":0,"count":125,"filter":"raw"}],"taxonomy_info":{"category":[{"value":2341,"label":"Check Valve"}],"post_tag":[{"value":158,"label":"check"},{"value":176,"label":"pump"},{"value":5,"label":"valve"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Do you need a check valve on a sump pump? - ZECO Valve<\/title>\n<meta name=\"description\" content=\"Sump pumps are critical systems that help prevent flooding in basements. But like any mechanical system, they can break down over time. One of the most important accessories you can install to protect your sump pump is a check valve. But do you really need one?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zecovalve.com\/pt\/do-you-need-a-check-valve-on-a-sump-pump.html\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Do you need a check valve on a sump pump? - ZECO Valve\" \/>\n<meta property=\"og:description\" content=\"Sump pumps are critical systems that help prevent flooding in basements. But like any mechanical system, they can break down over time. One of the most important accessories you can install to protect your sump pump is a check valve. But do you really need one?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zecovalve.com\/pt\/do-you-need-a-check-valve-on-a-sump-pump.html\" \/>\n<meta property=\"og:site_name\" content=\"ZECO Valve\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-16T15:32:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-16T15:32:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\">\n\t<meta name=\"twitter:data1\" content=\"ZECO Valve\">\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\">\n\t<meta name=\"twitter:data2\" content=\"4 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/zecovalve.com\/#website\",\"url\":\"https:\/\/zecovalve.com\/\",\"name\":\"ZECO Valve\",\"description\":\"Industrial Ball Valve, Gate Valve and Globe Valve Manufacturer\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/zecovalve.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html#primaryimage\",\"inLanguage\":\"pt-PT\",\"url\":\"https:\/\/zecovalve.com\/wp-content\/uploads\/2024\/06\/check-valve-on-a-sump-pump.jpg\",\"width\":1280,\"height\":720,\"caption\":\"check valve on a sump pump\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html#webpage\",\"url\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html\",\"name\":\"Do you need a check valve on a sump pump? - ZECO Valve\",\"isPartOf\":{\"@id\":\"https:\/\/zecovalve.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html#primaryimage\"},\"datePublished\":\"2024-06-16T15:32:24+00:00\",\"dateModified\":\"2024-06-16T15:32:27+00:00\",\"author\":{\"@id\":\"https:\/\/zecovalve.com\/#\/schema\/person\/0c958472facdf4ba16de226aa13985d0\"},\"description\":\"Sump pumps are critical systems that help prevent flooding in basements. But like any mechanical system, they can break down over time. One of the most important accessories you can install to protect your sump pump is a check valve. But do you really need one?\",\"breadcrumb\":{\"@id\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zecovalve.com\/\",\"url\":\"https:\/\/zecovalve.com\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html\",\"url\":\"https:\/\/zecovalve.com\/do-you-need-a-check-valve-on-a-sump-pump.html\",\"name\":\"Do you need a check valve on a sump pump?\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/zecovalve.com\/#\/schema\/person\/0c958472facdf4ba16de226aa13985d0\",\"name\":\"ZECO Valve\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/posts\/28297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/comments?post=28297"}],"version-history":[{"count":1,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/posts\/28297\/revisions"}],"predecessor-version":[{"id":28299,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/posts\/28297\/revisions\/28299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/media\/28298"}],"wp:attachment":[{"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/media?parent=28297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/categories?post=28297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zecovalve.com\/pt\/wp-json\/wp\/v2\/tags?post=28297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}